{"id":34186,"date":"2022-09-03T08:06:20","date_gmt":"2022-09-03T07:06:20","guid":{"rendered":"https:\/\/phillipreeve.net\/blog\/wp-content\/uploads\/2022\/09\/MS_35_1.4_Portra160_2.0_1.jpg"},"modified":"2022-09-03T08:06:30","modified_gmt":"2022-09-03T07:06:30","slug":"ms_35_1-4_portra160_2-0_1","status":"inherit","type":"attachment","link":"https:\/\/phillipreeve.net\/blog\/review-ms-optics-35mm-1-4-apoqualia\/ms_35_1-4_portra160_2-0_1\/","title":{"rendered":"MS_35_1.4_Portra160_2.0_1"},"author":4708,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"ngg_post_thumbnail":0},"class_list":["post-34186","attachment","type-attachment","status-inherit","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>MS_35_1.4_Portra160_2.0_1 - phillipreeve.net<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/phillipreeve.net\/blog\/wp-content\/uploads\/2022\/09\/MS_35_1.4_Portra160_2.0_1.jpg\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"MS_35_1.4_Portra160_2.0_1 - phillipreeve.net\" \/>\n<meta property=\"og:description\" content=\"Leica M6 | MS-Optics 35mm 1.4 Apoqualia | f\/2.0 | Portra 160\" \/>\n<meta property=\"og:url\" content=\"https:\/\/phillipreeve.net\/blog\/wp-content\/uploads\/2022\/09\/MS_35_1.4_Portra160_2.0_1.jpg\" \/>\n<meta property=\"og:site_name\" content=\"phillipreeve.net\" \/>\n<meta property=\"article:modified_time\" content=\"2022-09-03T07:06:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/phillipreeve.net\/blog\/wp-content\/uploads\/2022\/09\/MS_35_1.4_Portra160_2.0_1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"536\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/phillipreeve.net\/blog\/wp-content\/uploads\/2022\/09\/MS_35_1.4_Portra160_2.0_1.jpg\",\"url\":\"https:\/\/phillipreeve.net\/blog\/wp-content\/uploads\/2022\/09\/MS_35_1.4_Portra160_2.0_1.jpg\",\"name\":\"MS_35_1.4_Portra160_2.0_1 - phillipreeve.net\",\"isPartOf\":{\"@id\":\"https:\/\/phillipreeve.net\/blog\/#website\"},\"datePublished\":\"2022-09-03T07:06:20+00:00\",\"dateModified\":\"2022-09-03T07:06:30+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/phillipreeve.net\/blog\/wp-content\/uploads\/2022\/09\/MS_35_1.4_Portra160_2.0_1.jpg#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/phillipreeve.net\/blog\/wp-content\/uploads\/2022\/09\/MS_35_1.4_Portra160_2.0_1.jpg\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/phillipreeve.net\/blog\/wp-content\/uploads\/2022\/09\/MS_35_1.4_Portra160_2.0_1.jpg#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/phillipreeve.net\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Review: MS-Optics 35mm 1.4 Apoqualia\",\"item\":\"https:\/\/phillipreeve.net\/blog\/review-ms-optics-35mm-1-4-apoqualia\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"MS_35_1.4_Portra160_2.0_1\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/phillipreeve.net\/blog\/#website\",\"url\":\"https:\/\/phillipreeve.net\/blog\/\",\"name\":\"phillipreeve.net\",\"description\":\"Sony \u03b1 | Leica M | Nikon Z\/F New articles every week\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/phillipreeve.net\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"MS_35_1.4_Portra160_2.0_1 - phillipreeve.net","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/phillipreeve.net\/blog\/wp-content\/uploads\/2022\/09\/MS_35_1.4_Portra160_2.0_1.jpg","og_locale":"en_US","og_type":"article","og_title":"MS_35_1.4_Portra160_2.0_1 - phillipreeve.net","og_description":"Leica M6 | MS-Optics 35mm 1.4 Apoqualia | f\/2.0 | Portra 160","og_url":"https:\/\/phillipreeve.net\/blog\/wp-content\/uploads\/2022\/09\/MS_35_1.4_Portra160_2.0_1.jpg","og_site_name":"phillipreeve.net","article_modified_time":"2022-09-03T07:06:30+00:00","og_image":[{"width":800,"height":536,"url":"https:\/\/phillipreeve.net\/blog\/wp-content\/uploads\/2022\/09\/MS_35_1.4_Portra160_2.0_1.jpg","type":"image\/jpeg"}],"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/phillipreeve.net\/blog\/wp-content\/uploads\/2022\/09\/MS_35_1.4_Portra160_2.0_1.jpg","url":"https:\/\/phillipreeve.net\/blog\/wp-content\/uploads\/2022\/09\/MS_35_1.4_Portra160_2.0_1.jpg","name":"MS_35_1.4_Portra160_2.0_1 - phillipreeve.net","isPartOf":{"@id":"https:\/\/phillipreeve.net\/blog\/#website"},"datePublished":"2022-09-03T07:06:20+00:00","dateModified":"2022-09-03T07:06:30+00:00","breadcrumb":{"@id":"https:\/\/phillipreeve.net\/blog\/wp-content\/uploads\/2022\/09\/MS_35_1.4_Portra160_2.0_1.jpg#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/phillipreeve.net\/blog\/wp-content\/uploads\/2022\/09\/MS_35_1.4_Portra160_2.0_1.jpg"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/phillipreeve.net\/blog\/wp-content\/uploads\/2022\/09\/MS_35_1.4_Portra160_2.0_1.jpg#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/phillipreeve.net\/blog\/"},{"@type":"ListItem","position":2,"name":"Review: MS-Optics 35mm 1.4 Apoqualia","item":"https:\/\/phillipreeve.net\/blog\/review-ms-optics-35mm-1-4-apoqualia\/"},{"@type":"ListItem","position":3,"name":"MS_35_1.4_Portra160_2.0_1"}]},{"@type":"WebSite","@id":"https:\/\/phillipreeve.net\/blog\/#website","url":"https:\/\/phillipreeve.net\/blog\/","name":"phillipreeve.net","description":"Sony \u03b1 | Leica M | Nikon Z\/F New articles every week","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/phillipreeve.net\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/phillipreeve.net\/blog\/wp-content\/uploads\/2022\/09\/MS_35_1.4_Portra160_2.0_1.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"201\" src=\"https:\/\/phillipreeve.net\/blog\/wp-content\/uploads\/2022\/09\/MS_35_1.4_Portra160_2.0_1-300x201.jpg\" class=\"attachment-medium size-medium\" alt=\"ms-optics ms-optical apoqualia 35mm 1.4 fast noctilux angenieux leica m10 24mp 42mp review sharpness bokeh vignetting\" srcset=\"https:\/\/phillipreeve.net\/blog\/wp-content\/uploads\/2022\/09\/MS_35_1.4_Portra160_2.0_1-300x201.jpg 300w, https:\/\/phillipreeve.net\/blog\/wp-content\/uploads\/2022\/09\/MS_35_1.4_Portra160_2.0_1-768x515.jpg 768w, https:\/\/phillipreeve.net\/blog\/wp-content\/uploads\/2022\/09\/MS_35_1.4_Portra160_2.0_1.jpg 800w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>ms-optics ms-optical apoqualia 35mm 1.4 fast noctilux angenieux leica m10 24mp 42mp review sharpness bokeh vignetting<\/p>\n"},"caption":{"rendered":"<p>Leica M6 | MS-Optics 35mm 1.4 Apoqualia | f\/2.0 | Portra 160<\/p>\n"},"alt_text":"ms-optics ms-optical apoqualia 35mm 1.4 fast noctilux angenieux leica m10 24mp 42mp review sharpness bokeh vignetting","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":800,"height":536,"file":"2022\/09\/MS_35_1.4_Portra160_2.0_1.jpg","filesize":313177,"sizes":{"medium":{"file":"MS_35_1.4_Portra160_2.0_1-300x201.jpg","width":300,"height":201,"filesize":63086,"mime_type":"image\/jpeg","source_url":"https:\/\/phillipreeve.net\/blog\/wp-content\/uploads\/2022\/09\/MS_35_1.4_Portra160_2.0_1-300x201.jpg"},"thumbnail":{"file":"MS_35_1.4_Portra160_2.0_1-150x150.jpg","width":150,"height":150,"filesize":52379,"mime_type":"image\/jpeg","source_url":"https:\/\/phillipreeve.net\/blog\/wp-content\/uploads\/2022\/09\/MS_35_1.4_Portra160_2.0_1-150x150.jpg"},"medium_large":{"file":"MS_35_1.4_Portra160_2.0_1-768x515.jpg","width":768,"height":515,"filesize":127931,"mime_type":"image\/jpeg","source_url":"https:\/\/phillipreeve.net\/blog\/wp-content\/uploads\/2022\/09\/MS_35_1.4_Portra160_2.0_1-768x515.jpg"},"post-thumbnail":{"file":"MS_35_1.4_Portra160_2.0_1-672x372.jpg","width":672,"height":372,"filesize":98013,"mime_type":"image\/jpeg","source_url":"https:\/\/phillipreeve.net\/blog\/wp-content\/uploads\/2022\/09\/MS_35_1.4_Portra160_2.0_1-672x372.jpg"},"full":{"file":"MS_35_1.4_Portra160_2.0_1.jpg","width":800,"height":536,"mime_type":"image\/jpeg","source_url":"https:\/\/phillipreeve.net\/blog\/wp-content\/uploads\/2022\/09\/MS_35_1.4_Portra160_2.0_1.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"Digital Link","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":["MSOptics35_1.4","Portra160"]}},"post":32978,"source_url":"https:\/\/phillipreeve.net\/blog\/wp-content\/uploads\/2022\/09\/MS_35_1.4_Portra160_2.0_1.jpg","_links":{"self":[{"href":"https:\/\/phillipreeve.net\/blog\/wp-json\/wp\/v2\/media\/34186","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/phillipreeve.net\/blog\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/phillipreeve.net\/blog\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/phillipreeve.net\/blog\/wp-json\/wp\/v2\/users\/4708"}],"replies":[{"embeddable":true,"href":"https:\/\/phillipreeve.net\/blog\/wp-json\/wp\/v2\/comments?post=34186"}]}}