{"id":40870,"date":"2023-06-02T23:22:00","date_gmt":"2023-06-02T22:22:00","guid":{"rendered":"https:\/\/phillipreeve.net\/blog\/wp-content\/uploads\/2023\/06\/Meike_50mm_1.2_E_Sunstars_16.jpg"},"modified":"2023-06-03T13:03:20","modified_gmt":"2023-06-03T12:03:20","slug":"meike_50mm_1-2_e_sunstars_16","status":"inherit","type":"attachment","link":"https:\/\/phillipreeve.net\/blog\/review-meike-50mm-1-2\/meike_50mm_1-2_e_sunstars_16\/","title":{"rendered":"Meike_50mm_1.2_E_Sunstars_16"},"author":4708,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"ngg_post_thumbnail":0},"class_list":["post-40870","attachment","type-attachment","status-inherit","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Meike_50mm_1.2_E_Sunstars_16 - phillipreeve.net<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/phillipreeve.net\/blog\/wp-content\/uploads\/2023\/06\/Meike_50mm_1.2_E_Sunstars_16.jpg\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Meike_50mm_1.2_E_Sunstars_16 - phillipreeve.net\" \/>\n<meta property=\"og:description\" content=\"meike 50mm 1.2 e fe review 42mp 61mp sony a7riv coma bokeh fast resolution vignetting ca lateral\" \/>\n<meta property=\"og:url\" content=\"https:\/\/phillipreeve.net\/blog\/wp-content\/uploads\/2023\/06\/Meike_50mm_1.2_E_Sunstars_16.jpg\" \/>\n<meta property=\"og:site_name\" content=\"phillipreeve.net\" \/>\n<meta property=\"article:modified_time\" content=\"2023-06-03T12:03:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/phillipreeve.net\/blog\/wp-content\/uploads\/2023\/06\/Meike_50mm_1.2_E_Sunstars_16.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"534\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/phillipreeve.net\/blog\/wp-content\/uploads\/2023\/06\/Meike_50mm_1.2_E_Sunstars_16.jpg\",\"url\":\"https:\/\/phillipreeve.net\/blog\/wp-content\/uploads\/2023\/06\/Meike_50mm_1.2_E_Sunstars_16.jpg\",\"name\":\"Meike_50mm_1.2_E_Sunstars_16 - phillipreeve.net\",\"isPartOf\":{\"@id\":\"https:\/\/phillipreeve.net\/blog\/#website\"},\"datePublished\":\"2023-06-02T22:22:00+00:00\",\"dateModified\":\"2023-06-03T12:03:20+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/phillipreeve.net\/blog\/wp-content\/uploads\/2023\/06\/Meike_50mm_1.2_E_Sunstars_16.jpg#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/phillipreeve.net\/blog\/wp-content\/uploads\/2023\/06\/Meike_50mm_1.2_E_Sunstars_16.jpg\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/phillipreeve.net\/blog\/wp-content\/uploads\/2023\/06\/Meike_50mm_1.2_E_Sunstars_16.jpg#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/phillipreeve.net\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Review: Meike 50mm 1.2\",\"item\":\"https:\/\/phillipreeve.net\/blog\/review-meike-50mm-1-2\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Meike_50mm_1.2_E_Sunstars_16\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/phillipreeve.net\/blog\/#website\",\"url\":\"https:\/\/phillipreeve.net\/blog\/\",\"name\":\"phillipreeve.net\",\"description\":\"Sony \u03b1 | Leica M | Nikon Z\/F New articles every week\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/phillipreeve.net\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Meike_50mm_1.2_E_Sunstars_16 - phillipreeve.net","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/phillipreeve.net\/blog\/wp-content\/uploads\/2023\/06\/Meike_50mm_1.2_E_Sunstars_16.jpg","og_locale":"en_US","og_type":"article","og_title":"Meike_50mm_1.2_E_Sunstars_16 - phillipreeve.net","og_description":"meike 50mm 1.2 e fe review 42mp 61mp sony a7riv coma bokeh fast resolution vignetting ca lateral","og_url":"https:\/\/phillipreeve.net\/blog\/wp-content\/uploads\/2023\/06\/Meike_50mm_1.2_E_Sunstars_16.jpg","og_site_name":"phillipreeve.net","article_modified_time":"2023-06-03T12:03:20+00:00","og_image":[{"width":800,"height":534,"url":"https:\/\/phillipreeve.net\/blog\/wp-content\/uploads\/2023\/06\/Meike_50mm_1.2_E_Sunstars_16.jpg","type":"image\/jpeg"}],"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/phillipreeve.net\/blog\/wp-content\/uploads\/2023\/06\/Meike_50mm_1.2_E_Sunstars_16.jpg","url":"https:\/\/phillipreeve.net\/blog\/wp-content\/uploads\/2023\/06\/Meike_50mm_1.2_E_Sunstars_16.jpg","name":"Meike_50mm_1.2_E_Sunstars_16 - phillipreeve.net","isPartOf":{"@id":"https:\/\/phillipreeve.net\/blog\/#website"},"datePublished":"2023-06-02T22:22:00+00:00","dateModified":"2023-06-03T12:03:20+00:00","breadcrumb":{"@id":"https:\/\/phillipreeve.net\/blog\/wp-content\/uploads\/2023\/06\/Meike_50mm_1.2_E_Sunstars_16.jpg#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/phillipreeve.net\/blog\/wp-content\/uploads\/2023\/06\/Meike_50mm_1.2_E_Sunstars_16.jpg"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/phillipreeve.net\/blog\/wp-content\/uploads\/2023\/06\/Meike_50mm_1.2_E_Sunstars_16.jpg#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/phillipreeve.net\/blog\/"},{"@type":"ListItem","position":2,"name":"Review: Meike 50mm 1.2","item":"https:\/\/phillipreeve.net\/blog\/review-meike-50mm-1-2\/"},{"@type":"ListItem","position":3,"name":"Meike_50mm_1.2_E_Sunstars_16"}]},{"@type":"WebSite","@id":"https:\/\/phillipreeve.net\/blog\/#website","url":"https:\/\/phillipreeve.net\/blog\/","name":"phillipreeve.net","description":"Sony \u03b1 | Leica M | Nikon Z\/F New articles every week","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/phillipreeve.net\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/phillipreeve.net\/blog\/wp-content\/uploads\/2023\/06\/Meike_50mm_1.2_E_Sunstars_16.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/phillipreeve.net\/blog\/wp-content\/uploads\/2023\/06\/Meike_50mm_1.2_E_Sunstars_16-300x200.jpg\" class=\"attachment-medium size-medium\" alt=\"meike 50mm 1.2 e fe review 42mp 61mp sony a7riv coma bokeh fast resolution vignetting ca lateral\" srcset=\"https:\/\/phillipreeve.net\/blog\/wp-content\/uploads\/2023\/06\/Meike_50mm_1.2_E_Sunstars_16-300x200.jpg 300w, https:\/\/phillipreeve.net\/blog\/wp-content\/uploads\/2023\/06\/Meike_50mm_1.2_E_Sunstars_16-768x513.jpg 768w, https:\/\/phillipreeve.net\/blog\/wp-content\/uploads\/2023\/06\/Meike_50mm_1.2_E_Sunstars_16.jpg 800w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>meike 50mm 1.2 e fe review 42mp 61mp sony a7riv coma bokeh fast resolution vignetting ca lateral<\/p>\n"},"caption":{"rendered":"<p>meike 50mm 1.2 e fe review 42mp 61mp sony a7riv coma bokeh fast resolution vignetting ca lateral<\/p>\n"},"alt_text":"meike 50mm 1.2 e fe review 42mp 61mp sony a7riv coma bokeh fast resolution vignetting ca lateral","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":800,"height":534,"file":"2023\/06\/Meike_50mm_1.2_E_Sunstars_16.jpg","filesize":275599,"sizes":{"medium":{"file":"Meike_50mm_1.2_E_Sunstars_16-300x200.jpg","width":300,"height":200,"filesize":44379,"mime_type":"image\/jpeg","source_url":"https:\/\/phillipreeve.net\/blog\/wp-content\/uploads\/2023\/06\/Meike_50mm_1.2_E_Sunstars_16-300x200.jpg"},"thumbnail":{"file":"Meike_50mm_1.2_E_Sunstars_16-150x150.jpg","width":150,"height":150,"filesize":36107,"mime_type":"image\/jpeg","source_url":"https:\/\/phillipreeve.net\/blog\/wp-content\/uploads\/2023\/06\/Meike_50mm_1.2_E_Sunstars_16-150x150.jpg"},"medium_large":{"file":"Meike_50mm_1.2_E_Sunstars_16-768x513.jpg","width":768,"height":513,"filesize":103512,"mime_type":"image\/jpeg","source_url":"https:\/\/phillipreeve.net\/blog\/wp-content\/uploads\/2023\/06\/Meike_50mm_1.2_E_Sunstars_16-768x513.jpg"},"post-thumbnail":{"file":"Meike_50mm_1.2_E_Sunstars_16-672x372.jpg","width":672,"height":372,"filesize":80110,"mime_type":"image\/jpeg","source_url":"https:\/\/phillipreeve.net\/blog\/wp-content\/uploads\/2023\/06\/Meike_50mm_1.2_E_Sunstars_16-672x372.jpg"},"full":{"file":"Meike_50mm_1.2_E_Sunstars_16.jpg","width":800,"height":534,"mime_type":"image\/jpeg","source_url":"https:\/\/phillipreeve.net\/blog\/wp-content\/uploads\/2023\/06\/Meike_50mm_1.2_E_Sunstars_16.jpg"}},"image_meta":{"aperture":"0","credit":"Bastian Kratzke","camera":"ILCE-7RM2","caption":"","created_timestamp":"1685660980","copyright":"Bastian Kratzke","focal_length":"0","iso":"800","shutter_speed":"10","title":"","orientation":"0","keywords":[]}},"post":40843,"source_url":"https:\/\/phillipreeve.net\/blog\/wp-content\/uploads\/2023\/06\/Meike_50mm_1.2_E_Sunstars_16.jpg","_links":{"self":[{"href":"https:\/\/phillipreeve.net\/blog\/wp-json\/wp\/v2\/media\/40870","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/phillipreeve.net\/blog\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/phillipreeve.net\/blog\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/phillipreeve.net\/blog\/wp-json\/wp\/v2\/users\/4708"}],"replies":[{"embeddable":true,"href":"https:\/\/phillipreeve.net\/blog\/wp-json\/wp\/v2\/comments?post=40870"}]}}